{"id":3216,"date":"2026-07-07T09:20:11","date_gmt":"2026-07-07T08:20:11","guid":{"rendered":"https:\/\/offy.pt\/?page_id=3216"},"modified":"2026-07-22T11:29:46","modified_gmt":"2026-07-22T10:29:46","slug":"teclados-pixie-tab","status":"publish","type":"page","link":"https:\/\/offy.pt\/index.php\/teclados-pixie-tab\/","title":{"rendered":"Pixie Tab &#8211; PT"},"content":{"rendered":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; vertically_center_columns=&#8221;true&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding_tablet=&#8221;20&#8243; bottom_padding_tablet=&#8221;20&#8243; left_padding_tablet=&#8221;20&#8243; right_padding_tablet=&#8221;20&#8243; top_padding_phone=&#8221;20&#8243; bottom_padding_phone=&#8221;20&#8243; left_padding_phone=&#8221;20&#8243; right_padding_phone=&#8221;20&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; class=&#8221;product-row&#8221; id=&#8221;product-row&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column top_padding_desktop=&#8221;0&#8243; bottom_padding_desktop=&#8221;0&#8243; left_padding_desktop=&#8221;0&#8243; right_padding_desktop=&#8221;0&#8243; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;advanced&#8221; border_right_desktop=&#8221;1px&#8221; border_bottom_desktop=&#8221;0&#8243; border_left_phone=&#8221;0&#8243; border_top_phone=&#8221;0&#8243; border_right_phone=&#8221;0&#8243; border_bottom_phone=&#8221;0&#8243; column_border_color=&#8221;#efefef&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221; content_layout=&#8221;default&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;5&#8243;]\r\n    <div id=\"agpg-6a97be24346c1\"\r\n         class=\"ag-product-gallery ag-thumb-bottom \"\r\n         style=\"width:100%;\">\r\n\r\n        <div class=\"ag-gallery-inner ag-bottom\">\r\n\r\n            \r\n            <div class=\"ag-main-wrap ag-arrow-light\"\r\n                 style=\"max-height:800px;background:#FFFFFF;border-radius:10px;\"\r\n                 data-urls=\"[&quot;https:\\\/\\\/offy.pt\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/6.jpg&quot;,&quot;https:\\\/\\\/offy.pt\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/9.jpg&quot;,&quot;https:\\\/\\\/offy.pt\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/5.jpg&quot;,&quot;https:\\\/\\\/offy.pt\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/10.jpg&quot;,&quot;https:\\\/\\\/offy.pt\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/7.jpg&quot;,&quot;https:\\\/\\\/offy.pt\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/8.jpg&quot;,&quot;https:\\\/\\\/offy.pt\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/3.jpg&quot;,&quot;https:\\\/\\\/offy.pt\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/4.jpg&quot;,&quot;https:\\\/\\\/offy.pt\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/2.jpg&quot;,&quot;https:\\\/\\\/offy.pt\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/1.jpg&quot;,&quot;https:\\\/\\\/offy.pt\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/lexi_9.jpg&quot;]\"\r\n                 data-large=\"[&quot;https:\\\/\\\/offy.pt\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/6-1024x1024.jpg&quot;,&quot;https:\\\/\\\/offy.pt\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/9-1024x1024.jpg&quot;,&quot;https:\\\/\\\/offy.pt\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/5-1024x1024.jpg&quot;,&quot;https:\\\/\\\/offy.pt\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/10-1024x1024.jpg&quot;,&quot;https:\\\/\\\/offy.pt\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/7-1024x1024.jpg&quot;,&quot;https:\\\/\\\/offy.pt\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/8-1024x1024.jpg&quot;,&quot;https:\\\/\\\/offy.pt\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/3-1024x1024.jpg&quot;,&quot;https:\\\/\\\/offy.pt\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/4-1024x1024.jpg&quot;,&quot;https:\\\/\\\/offy.pt\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/2-1024x1024.jpg&quot;,&quot;https:\\\/\\\/offy.pt\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/1-1024x1024.jpg&quot;,&quot;https:\\\/\\\/offy.pt\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/lexi_9-1024x1024.jpg&quot;]\">\r\n\r\n                <button class=\"ag-arr ag-arr-prev\" aria-label=\"Previous image\">\r\n                    <svg width=\"20\" height=\"20\" viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"2.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><polyline points=\"15 18 9 12 15 6\"\/><\/svg>\r\n                <\/button>\r\n\r\n                <img decoding=\"async\" class=\"ag-main-img\"\r\n                     src=\"https:\/\/offy.pt\/wp-content\/uploads\/2026\/07\/6-1024x1024.jpg\"\r\n                     alt=\"\">\r\n\r\n                <button class=\"ag-arr ag-arr-next\" aria-label=\"Next image\">\r\n                    <svg width=\"20\" height=\"20\" viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"2.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg>\r\n                <\/button>\r\n\r\n                <button class=\"ag-zoom-btn\" aria-label=\"Zoom image\">\r\n                    <svg width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><circle cx=\"11\" cy=\"11\" r=\"8\"\/><line x1=\"21\" y1=\"21\" x2=\"16.65\" y2=\"16.65\"\/><line x1=\"11\" y1=\"8\" x2=\"11\" y2=\"14\"\/><line x1=\"8\" y1=\"11\" x2=\"14\" y2=\"11\"\/><\/svg>\r\n                <\/button>\r\n\r\n                                <div class=\"ag-dots\">\r\n                                        <span class=\"ag-dot active\"\r\n                          data-index=\"0\"><\/span>\r\n                                        <span class=\"ag-dot\"\r\n                          data-index=\"1\"><\/span>\r\n                                        <span class=\"ag-dot\"\r\n                          data-index=\"2\"><\/span>\r\n                                        <span class=\"ag-dot\"\r\n                          data-index=\"3\"><\/span>\r\n                                        <span class=\"ag-dot\"\r\n                          data-index=\"4\"><\/span>\r\n                                        <span class=\"ag-dot\"\r\n                          data-index=\"5\"><\/span>\r\n                                        <span class=\"ag-dot\"\r\n                          data-index=\"6\"><\/span>\r\n                                        <span class=\"ag-dot\"\r\n                          data-index=\"7\"><\/span>\r\n                                        <span class=\"ag-dot\"\r\n                          data-index=\"8\"><\/span>\r\n                                        <span class=\"ag-dot\"\r\n                          data-index=\"9\"><\/span>\r\n                                        <span class=\"ag-dot\"\r\n                          data-index=\"10\"><\/span>\r\n                                    <\/div>\r\n                \r\n            <\/div>\r\n\r\n                        <div class=\"ag-thumb-rail\" style=\"justify-content:flex-start;\">\r\n                                <div class=\"ag-thumb active\"\r\n                     data-index=\"0\"\r\n                     style=\"width:60px;height:60px;border-radius:10px;flex-shrink:0;\">\r\n                    <img decoding=\"async\" src=\"https:\/\/offy.pt\/wp-content\/uploads\/2026\/07\/6-150x150.jpg\" alt=\"\">\r\n                <\/div>\r\n                                <div class=\"ag-thumb\"\r\n                     data-index=\"1\"\r\n                     style=\"width:60px;height:60px;border-radius:10px;flex-shrink:0;\">\r\n                    <img decoding=\"async\" src=\"https:\/\/offy.pt\/wp-content\/uploads\/2026\/07\/9-150x150.jpg\" alt=\"\">\r\n                <\/div>\r\n                                <div class=\"ag-thumb\"\r\n                     data-index=\"2\"\r\n                     style=\"width:60px;height:60px;border-radius:10px;flex-shrink:0;\">\r\n                    <img decoding=\"async\" src=\"https:\/\/offy.pt\/wp-content\/uploads\/2026\/07\/5-150x150.jpg\" alt=\"\">\r\n                <\/div>\r\n                                <div class=\"ag-thumb\"\r\n                     data-index=\"3\"\r\n                     style=\"width:60px;height:60px;border-radius:10px;flex-shrink:0;\">\r\n                    <img decoding=\"async\" src=\"https:\/\/offy.pt\/wp-content\/uploads\/2026\/07\/10-150x150.jpg\" alt=\"\">\r\n                <\/div>\r\n                                <div class=\"ag-thumb\"\r\n                     data-index=\"4\"\r\n                     style=\"width:60px;height:60px;border-radius:10px;flex-shrink:0;\">\r\n                    <img decoding=\"async\" src=\"https:\/\/offy.pt\/wp-content\/uploads\/2026\/07\/7-150x150.jpg\" alt=\"\">\r\n                <\/div>\r\n                                <div class=\"ag-thumb\"\r\n                     data-index=\"5\"\r\n                     style=\"width:60px;height:60px;border-radius:10px;flex-shrink:0;\">\r\n                    <img decoding=\"async\" src=\"https:\/\/offy.pt\/wp-content\/uploads\/2026\/07\/8-150x150.jpg\" alt=\"\">\r\n                <\/div>\r\n                                <div class=\"ag-thumb\"\r\n                     data-index=\"6\"\r\n                     style=\"width:60px;height:60px;border-radius:10px;flex-shrink:0;\">\r\n                    <img decoding=\"async\" src=\"https:\/\/offy.pt\/wp-content\/uploads\/2026\/07\/3-150x150.jpg\" alt=\"\">\r\n                <\/div>\r\n                                <div class=\"ag-thumb\"\r\n                     data-index=\"7\"\r\n                     style=\"width:60px;height:60px;border-radius:10px;flex-shrink:0;\">\r\n                    <img decoding=\"async\" src=\"https:\/\/offy.pt\/wp-content\/uploads\/2026\/07\/4-150x150.jpg\" alt=\"\">\r\n                <\/div>\r\n                                <div class=\"ag-thumb\"\r\n                     data-index=\"8\"\r\n                     style=\"width:60px;height:60px;border-radius:10px;flex-shrink:0;\">\r\n                    <img decoding=\"async\" src=\"https:\/\/offy.pt\/wp-content\/uploads\/2026\/07\/2-150x150.jpg\" alt=\"\">\r\n                <\/div>\r\n                                <div class=\"ag-thumb\"\r\n                     data-index=\"9\"\r\n                     style=\"width:60px;height:60px;border-radius:10px;flex-shrink:0;\">\r\n                    <img decoding=\"async\" src=\"https:\/\/offy.pt\/wp-content\/uploads\/2026\/07\/1-150x150.jpg\" alt=\"\">\r\n                <\/div>\r\n                                <div class=\"ag-thumb\"\r\n                     data-index=\"10\"\r\n                     style=\"width:60px;height:60px;border-radius:10px;flex-shrink:0;\">\r\n                    <img decoding=\"async\" src=\"https:\/\/offy.pt\/wp-content\/uploads\/2026\/07\/lexi_9-150x150.jpg\" alt=\"\">\r\n                <\/div>\r\n                            <\/div>\r\n            \r\n        <\/div>\r\n\r\n                <div class=\"ag-lightbox\" id=\"lb-agpg-6a97be24346c1\" aria-hidden=\"true\" data-gallery=\"agpg-6a97be24346c1\">\r\n            <button class=\"ag-lb-close\" aria-label=\"Close\">\r\n                <svg width=\"22\" height=\"22\" viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"2.5\" stroke-linecap=\"round\"><line x1=\"18\" y1=\"6\" x2=\"6\" y2=\"18\"\/><line x1=\"6\" y1=\"6\" x2=\"18\" y2=\"18\"\/><\/svg>\r\n            <\/button>\r\n            <button class=\"ag-lb-nav ag-lb-prev\" aria-label=\"Previous\">\r\n                <svg width=\"26\" height=\"26\" viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"2.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><polyline points=\"15 18 9 12 15 6\"\/><\/svg>\r\n            <\/button>\r\n            <div class=\"ag-lb-inner\">\r\n                <img decoding=\"async\" class=\"ag-lb-img\" src=\"https:\/\/offy.pt\/wp-content\/uploads\/2026\/07\/6.jpg\" alt=\"\">\r\n            <\/div>\r\n            <button class=\"ag-lb-nav ag-lb-next\" aria-label=\"Next\">\r\n                <svg width=\"26\" height=\"26\" viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"2.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg>\r\n            <\/button>\r\n            <div class=\"ag-lb-counter\">1 \/ 11<\/div>\r\n        <\/div>\r\n\r\n    <\/div>\r\n\r\n    [divider line_type=&#8221;No Line&#8221; custom_height=&#8221;60&#8243;][\/vc_column][vc_column left_padding_desktop=&#8221;50&#8243; right_padding_desktop=&#8221;50&#8243; top_padding_tablet=&#8221;0&#8243; bottom_padding_tablet=&#8221;0&#8243; left_padding_tablet=&#8221;0&#8243; right_padding_tablet=&#8221;0&#8243; top_padding_phone=&#8221;0&#8243; bottom_padding_phone=&#8221;0&#8243; left_padding_phone=&#8221;0&#8243; right_padding_phone=&#8221;0&#8243; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;10px&#8221; desktop_text_alignment=&#8221;left&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221; content_layout=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Teclado sem fios<\/p>\n<h1 style=\"text-align: left;\"><span style=\"color: #009cdb;\">PIXIE TAB<\/span><\/h1>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;2%&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;no-extra-padding&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#F2F2F2&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;20px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<div style=\"display: flex; align-items: center; gap: 5px; border-radius: 16px;\">\n<p><img loading=\"lazy\" decoding=\"async\" style=\"flex-shrink: 0;\" src=\"https:\/\/offy.pt\/wp-content\/uploads\/2026\/07\/2-01.png\" alt=\"Bluetooth\" width=\"40\" height=\"40\" \/><\/p>\n<div style=\"margin: 0; line-height: 1.5; color: #4a4a6a; letter-spacing: 0.5px;\">MODO DUPLO: 2.4 GHZ E BLUETOOTH<\/div>\n<\/div>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;20px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;extra_row_spacer&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;no-extra-padding&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#F2F2F2&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;20px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<div style=\"display: flex; align-items: center; gap: 5px; border-radius: 16px;\">\n<p><img loading=\"lazy\" decoding=\"async\" style=\"flex-shrink: 0;\" src=\"https:\/\/offy.pt\/wp-content\/uploads\/2026\/07\/2-02.png\" alt=\"Bluetooth\" width=\"40\" height=\"40\" \/><\/p>\n<div style=\"margin: 0; line-height: 1.5; color: #4a4a6a; letter-spacing: 0.5px;\">COMPATIBILIDADE MULTI-DISPOSITIVO<\/div>\n<\/div>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;no-extra-padding&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#F2F2F2&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;20px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<div style=\"display: flex; align-items: center; gap: 5px; border-radius: 16px;\">\n<p><img loading=\"lazy\" decoding=\"async\" style=\"flex-shrink: 0;\" src=\"https:\/\/offy.pt\/wp-content\/uploads\/2026\/07\/2-06.png\" alt=\"Bluetooth\" width=\"40\" height=\"40\" \/><\/p>\n<div style=\"margin: 0; line-height: 1.5; color: #4a4a6a; letter-spacing: 0.5px;\">FUN\u00c7\u00d5ES DE ATALHO FN<\/div>\n<\/div>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;20px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;extra_row_spacer&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;no-extra-padding&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#F2F2F2&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;20px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<div style=\"display: flex; align-items: center; gap: 5px; border-radius: 16px;\">\n<p><img loading=\"lazy\" decoding=\"async\" style=\"flex-shrink: 0;\" src=\"https:\/\/offy.pt\/wp-content\/uploads\/2026\/07\/2-08.png\" alt=\"Bluetooth\" width=\"40\" height=\"40\" \/><\/p>\n<div style=\"margin: 0; line-height: 1.5; color: #4a4a6a; letter-spacing: 0.5px;\">SUPORTE PARA TABLET<\/div>\n<\/div>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;1%&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;Full Width Line&#8221; line_thickness=&#8221;1&#8243; divider_color=&#8221;extra-color-1&#8243; custom_height=&#8221;2%&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;1%&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<p style=\"font-size: 17px; text-align: left;\">Teclado sem fios com suporte integrado para tablet. Destaca-se pela conetividade, permitindo alternar entre 4 dispositivos (1 via recetor 2.4 GHz e 3 via Bluetooth). Possui bateria recarreg\u00e1vel com 150 horas de autonomia e \u00e9 compat\u00edvel com Windows, Mac, Linux, iPadOS e Android.<\/p>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;10px&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#F2F2F2&#8243; scene_position=&#8221;center&#8221; left_padding_desktop=&#8221;15%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;15%&#8221; left_padding_tablet=&#8221;0&#8243; right_padding_tablet=&#8221;0&#8243; left_padding_phone=&#8221;0&#8243; right_padding_phone=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_color=&#8221;#ffffff&#8221; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;50%&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;waves_opacity_alt&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][\/vc_column][vc_column column_padding=&#8221;padding-1-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;padding-3-percent&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;descricao&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;advanced&#8221; border_bottom_desktop=&#8221;1px&#8221; column_border_color=&#8221;#DEDEDE&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; content_layout=&#8221;default&#8221;][vc_raw_html css=&#8221;&#8221;]JTNDc3R5bGUlM0UlMEQlMEElMjAlMjAuYW5jaG9yLWxpbmslMjAlN0IlMEQlMEElMjAlMjAlMjAlMjBkaXNwbGF5JTNBJTIwaW5saW5lLWZsZXglM0IlMEQlMEElMjAlMjAlMjAlMjBmbGV4LWRpcmVjdGlvbiUzQSUyMGNvbHVtbiUzQiUwRCUwQSUyMCUyMCUyMCUyMGFsaWduLWl0ZW1zJTNBJTIwY2VudGVyJTNCJTBEJTBBJTIwJTIwJTIwJTIwZ2FwJTNBJTIwNHB4JTNCJTBEJTBBJTIwJTIwJTIwJTIwdGV4dC1kZWNvcmF0aW9uJTNBJTIwbm9uZSUzQiUwRCUwQSUyMCUyMCUyMCUyMGNvbG9yJTNBJTIwJTIzNDQ0NDQlM0IlMEQlMEElMjAlMjAlMjAlMjBmb250LXNpemUlM0ElMjAxNHB4JTNCJTBEJTBBJTIwJTIwJTIwJTIwZm9udC13ZWlnaHQlM0ElMjA1MDAlM0IlMEQlMEElMjAlMjAlMjAlMjB0cmFuc2l0aW9uJTNBJTIwY29sb3IlMjAwLjE1cyUzQiUwRCUwQSUyMCUyMCU3RCUwRCUwQSUyMCUyMC5hbmNob3ItbGluayUzQWhvdmVyJTIwJTdCJTBEJTBBJTIwJTIwJTIwJTIwY29sb3IlM0ElMjAlMjMwMDljZGIlM0IlMEQlMEElMjAlMjAlN0QlMEQlMEElMjAlMjAuYW5jaG9yLWxpbmslMjBzdmclMjAlN0IlMEQlMEElMjAlMjAlMjAlMjBkaXNwbGF5JTNBJTIwYmxvY2slM0IlMEQlMEElMjAlMjAlN0QlMEQlMEElM0MlMkZzdHlsZSUzRSUwRCUwQSUwRCUwQSUzQ2ElMjBocmVmJTNEJTIyJTIzZGVzY3JpY2FvJTIyJTIwY2xhc3MlM0QlMjJhbmNob3ItbGluayUyMiUzRSUwRCUwQSUyMCUyMERFU0NSSSVDMyU4NyVDMyU4M08lMEQlMEElMjAlMjAlM0NzdmclMjB3aWR0aCUzRCUyMjEyJTIyJTIwaGVpZ2h0JTNEJTIyOCUyMiUyMHZpZXdCb3glM0QlMjIwJTIwMCUyMDEyJTIwOCUyMiUyMGZpbGwlM0QlMjJub25lJTIyJTNFJTBEJTBBJTIwJTIwJTIwJTIwJTNDcGF0aCUyMGQlM0QlMjJNMSUyMDEuNUw2JTIwNi41TDExJTIwMS41JTIyJTIwc3Ryb2tlJTNEJTIyY3VycmVudENvbG9yJTIyJTIwc3Ryb2tlLXdpZHRoJTNEJTIyMS41JTIyJTIwc3Ryb2tlLWxpbmVjYXAlM0QlMjJyb3VuZCUyMiUyMHN0cm9rZS1saW5lam9pbiUzRCUyMnJvdW5kJTIyJTJGJTNFJTBEJTBBJTIwJTIwJTNDJTJGc3ZnJTNFJTBEJTBBJTNDJTJGYSUzRQ==[\/vc_raw_html][\/vc_column][vc_column column_padding=&#8221;padding-1-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;padding-3-percent&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;especificacao&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;advanced&#8221; border_bottom_desktop=&#8221;1px&#8221; column_border_color=&#8221;#DEDEDE&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; content_layout=&#8221;default&#8221;][vc_raw_html css=&#8221;&#8221;]JTNDc3R5bGUlM0UlMEQlMEElMjAlMjAuYW5jaG9yLWxpbmslMjAlN0IlMEQlMEElMjAlMjAlMjAlMjBkaXNwbGF5JTNBJTIwaW5saW5lLWZsZXglM0IlMEQlMEElMjAlMjAlMjAlMjBmbGV4LWRpcmVjdGlvbiUzQSUyMGNvbHVtbiUzQiUwRCUwQSUyMCUyMCUyMCUyMGFsaWduLWl0ZW1zJTNBJTIwY2VudGVyJTNCJTBEJTBBJTIwJTIwJTIwJTIwZ2FwJTNBJTIwNHB4JTNCJTBEJTBBJTIwJTIwJTIwJTIwdGV4dC1kZWNvcmF0aW9uJTNBJTIwbm9uZSUzQiUwRCUwQSUyMCUyMCUyMCUyMGNvbG9yJTNBJTIwJTIzMTExJTNCJTBEJTBBJTIwJTIwJTIwJTIwZm9udC1zaXplJTNBJTIwMTRweCUzQiUwRCUwQSUyMCUyMCUyMCUyMGZvbnQtd2VpZ2h0JTNBJTIwNTAwJTNCJTBEJTBBJTIwJTIwJTIwJTIwdHJhbnNpdGlvbiUzQSUyMGNvbG9yJTIwMC4xNXMlM0IlMEQlMEElMjAlMjAlN0QlMEQlMEElMjAlMjAuYW5jaG9yLWxpbmslM0Fob3ZlciUyMCU3QiUwRCUwQSUyMCUyMCUyMCUyMGNvbG9yJTNBJTIwJTIzMDA5Y2RiJTNCJTBEJTBBJTIwJTIwJTdEJTBEJTBBJTIwJTIwLmFuY2hvci1saW5rJTIwc3ZnJTIwJTdCJTBEJTBBJTIwJTIwJTIwJTIwZGlzcGxheSUzQSUyMGJsb2NrJTNCJTBEJTBBJTIwJTIwJTdEJTBEJTBBJTNDJTJGc3R5bGUlM0UlMEQlMEElMEQlMEElM0NhJTIwaHJlZiUzRCUyMiUyM2VzcGVjaWZpY2Fjb2VzJTIyJTIwY2xhc3MlM0QlMjJhbmNob3ItbGluayUyMiUzRSUwRCUwQUVTUEVDSUZJQ0ElQzMlODclQzMlOTVFUyUwRCUwQSUyMCUyMCUzQ3N2ZyUyMHdpZHRoJTNEJTIyMTIlMjIlMjBoZWlnaHQlM0QlMjI4JTIyJTIwdmlld0JveCUzRCUyMjAlMjAwJTIwMTIlMjA4JTIyJTIwZmlsbCUzRCUyMm5vbmUlMjIlM0UlMEQlMEElMjAlMjAlMjAlMjAlM0NwYXRoJTIwZCUzRCUyMk0xJTIwMS41TDYlMjA2LjVMMTElMjAxLjUlMjIlMjBzdHJva2UlM0QlMjJjdXJyZW50Q29sb3IlMjIlMjBzdHJva2Utd2lkdGglM0QlMjIxLjUlMjIlMjBzdHJva2UtbGluZWNhcCUzRCUyMnJvdW5kJTIyJTIwc3Ryb2tlLWxpbmVqb2luJTNEJTIycm91bmQlMjIlMkYlM0UlMEQlMEElMjAlMjAlM0MlMkZzdmclM0UlMEQlMEElM0MlMkZhJTNF[\/vc_raw_html][\/vc_column][vc_column column_padding=&#8221;padding-1-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;padding-3-percent&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;downloads&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;advanced&#8221; border_bottom_desktop=&#8221;1px&#8221; column_border_color=&#8221;#DEDEDE&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; content_layout=&#8221;default&#8221;][vc_raw_html css=&#8221;&#8221;]JTNDc3R5bGUlM0UlMEQlMEElMjAlMjAuYW5jaG9yLWxpbmslMjAlN0IlMEQlMEElMjAlMjAlMjAlMjBkaXNwbGF5JTNBJTIwaW5saW5lLWZsZXglM0IlMEQlMEElMjAlMjAlMjAlMjBmbGV4LWRpcmVjdGlvbiUzQSUyMGNvbHVtbiUzQiUwRCUwQSUyMCUyMCUyMCUyMGFsaWduLWl0ZW1zJTNBJTIwY2VudGVyJTNCJTBEJTBBJTIwJTIwJTIwJTIwZ2FwJTNBJTIwNHB4JTNCJTBEJTBBJTIwJTIwJTIwJTIwdGV4dC1kZWNvcmF0aW9uJTNBJTIwbm9uZSUzQiUwRCUwQSUyMCUyMCUyMCUyMGNvbG9yJTNBJTIwJTIzMTExJTNCJTBEJTBBJTIwJTIwJTIwJTIwZm9udC1zaXplJTNBJTIwMTRweCUzQiUwRCUwQSUyMCUyMCUyMCUyMGZvbnQtd2VpZ2h0JTNBJTIwNTAwJTNCJTBEJTBBJTIwJTIwJTIwJTIwdHJhbnNpdGlvbiUzQSUyMGNvbG9yJTIwMC4xNXMlM0IlMEQlMEElMjAlMjAlN0QlMEQlMEElMjAlMjAuYW5jaG9yLWxpbmslM0Fob3ZlciUyMCU3QiUwRCUwQSUyMCUyMCUyMCUyMGNvbG9yJTNBJTIwJTIzMDA5Y2RiJTNCJTBEJTBBJTIwJTIwJTdEJTBEJTBBJTIwJTIwLmFuY2hvci1saW5rJTIwc3ZnJTIwJTdCJTBEJTBBJTIwJTIwJTIwJTIwZGlzcGxheSUzQSUyMGJsb2NrJTNCJTBEJTBBJTIwJTIwJTdEJTBEJTBBJTNDJTJGc3R5bGUlM0UlMEQlMEElMEQlMEElM0NhJTIwaHJlZiUzRCUyMiUyM2Rvd25sb2FkcyUyMiUyMGNsYXNzJTNEJTIyYW5jaG9yLWxpbmslMjIlM0UlMEQlMEFET1dOTE9BRFMlMEQlMEElMjAlMjAlM0NzdmclMjB3aWR0aCUzRCUyMjEyJTIyJTIwaGVpZ2h0JTNEJTIyOCUyMiUyMHZpZXdCb3glM0QlMjIwJTIwMCUyMDEyJTIwOCUyMiUyMGZpbGwlM0QlMjJub25lJTIyJTNFJTBEJTBBJTIwJTIwJTIwJTIwJTNDcGF0aCUyMGQlM0QlMjJNMSUyMDEuNUw2JTIwNi41TDExJTIwMS41JTIyJTIwc3Ryb2tlJTNEJTIyY3VycmVudENvbG9yJTIyJTIwc3Ryb2tlLXdpZHRoJTNEJTIyMS41JTIyJTIwc3Ryb2tlLWxpbmVjYXAlM0QlMjJyb3VuZCUyMiUyMHN0cm9rZS1saW5lam9pbiUzRCUyMnJvdW5kJTIyJTJGJTNFJTBEJTBBJTIwJTIwJTNDJTJGc3ZnJTNFJTBEJTBBJTNDJTJGYSUzRQ==[\/vc_raw_html][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding_phone=&#8221;5%&#8221; bottom_padding_phone=&#8221;5%&#8221; left_padding_phone=&#8221;5%&#8221; right_padding_phone=&#8221;5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; id=&#8221;descricao&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column left_padding_desktop=&#8221;20%&#8221; right_padding_desktop=&#8221;20%&#8221; left_padding_tablet=&#8221;0&#8243; right_padding_tablet=&#8221;0&#8243; left_padding_phone=&#8221;0&#8243; right_padding_phone=&#8221;0&#8243; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;30px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;5%&#8221; bottom_padding=&#8221;5%&#8221; top_padding_tablet=&#8221;30px&#8221; bottom_padding_tablet=&#8221;0&#8243; top_padding_phone=&#8221;30px&#8221; bottom_padding_phone=&#8221;0&#8243; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner left_padding_desktop=&#8221;2%&#8221; right_padding_desktop=&#8221;2%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;0px&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;center&#8221; tablet_text_alignment=&#8221;left&#8221; phone_text_alignment=&#8221;left&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h2><span style=\"color: #009cdb; font-size: 40px;\">A melhor metade do seu tablet<\/span><\/h2>\n[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<p style=\"font-size: 17px;\">Este teclado \u00e9 mais do que um acess\u00f3rio; \u00e9 uma melhoria estrutural para a sua configura\u00e7\u00e3o m\u00f3vel. Ao integrar um suporte robusto e n\u00e3o remov\u00edvel diretamente na estrutura do teclado, cri\u00e1mos uma esta\u00e7\u00e3o de trabalho unificada que se mant\u00e9m est\u00e1vel em qualquer superf\u00edcie. O seu perfil fino de 12 mm garante que toda a sua experi\u00eancia de &#8220;desktop&#8221; continua port\u00e1til o suficiente para caber numa capa de tablet.<\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][nectar_video_player_self_hosted video_mp4=&#8221;https:\/\/offy.pt\/wp-content\/uploads\/2026\/07\/0001_5.mp4&#8243; align=&#8221;center&#8221; player_functionality=&#8221;default&#8221; hide_controls=&#8221;yes&#8221; loop=&#8221;yes&#8221; autoplay=&#8221;yes&#8221; video_loading=&#8221;default&#8221; border_radius=&#8221;20px&#8221; box_shadow=&#8221;none&#8221; advanced_gradient_display_type=&#8221;linear&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;30px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;column_reverse&#8221; top_padding=&#8221;5%&#8221; bottom_padding=&#8221;5%&#8221; top_padding_phone=&#8221;0&#8243; bottom_padding_phone=&#8221;0&#8243; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;3250&#8243; image_size=&#8221;large&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;20px&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][\/vc_column_inner][vc_column_inner left_padding_desktop=&#8221;2%&#8221; right_padding_desktop=&#8221;2%&#8221; bottom_padding_phone=&#8221;30px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;0px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h2><span style=\"color: #009cdb; font-size: 40px;\">Estabilidade que nunca o abandona<\/span><\/h2>\n[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<p style=\"font-size: 17px;\">Deixe de procurar suportes improvisados ou capas pouco fi\u00e1veis. O suporte dobr\u00e1vel integrado foi concebido para suportar o peso dos tablets modernos, oferecendo um \u00e2ngulo fixo e ergon\u00f3mico que n\u00e3o desliza nem colapsa enquanto escreve. Por ser uma parte permanente do teclado, garante-lhe uma configura\u00e7\u00e3o consistente e resistente sempre que abre a sua mala.<\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;30px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding=&#8221;5%&#8221; bottom_padding_phone=&#8221;0&#8243; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner left_padding_desktop=&#8221;2%&#8221; right_padding_desktop=&#8221;2%&#8221; bottom_padding_phone=&#8221;30px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h2><span style=\"color: #009cdb; font-size: 40px;\">Controlo eficiente ao alcance dos seus dedos<\/span><\/h2>\n[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<p style=\"font-size: 17px;\">Acelere as suas tarefas com um layout pensado para a conveni\u00eancia. As 13 teclas de atalho Fn oferecem acesso imediato a comandos essenciais, incluindo reprodu\u00e7\u00e3o multim\u00e9dia, ajuste de volume, brilho do ecr\u00e3 e bloqueio do sistema. Estas fun\u00e7\u00f5es eliminam a necessidade de navegar por menus complexos, permitindo-lhe gerir o seu ambiente com menos toques no teclado.<\/p>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;0px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;3264&#8243; image_size=&#8221;large&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;20px&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;column_reverse&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;0&#8243; bottom_padding=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;both&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;fade-in&#8221; shape_type=&#8221;curve&#8221; gradient_type=&#8221;default&#8221;][vc_column top_padding_desktop=&#8221;70&#8243; bottom_padding_desktop=&#8221;70&#8243; left_padding_desktop=&#8221;70&#8243; right_padding_desktop=&#8221;70&#8243; top_padding_phone=&#8221;20&#8243; bottom_padding_phone=&#8221;20&#8243; left_padding_phone=&#8221;20&#8243; right_padding_phone=&#8221;20&#8243; top_margin=&#8221;0&#8243; bottom_margin=&#8221;0&#8243; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#cfe6f6&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;3px&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;bloco_redondo&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;3262&#8243; image_size=&#8221;full&#8221; max_width=&#8221;custom&#8221; animation_type=&#8221;looped&#8221; loop_animation=&#8221;none&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; image_loading=&#8221;default&#8221; el_class=&#8221;mesa_altura&#8221; max_width_custom=&#8221;768&#8243;][\/vc_column][vc_column right_padding_desktop=&#8221;35%&#8221; top_padding_tablet=&#8221;10%&#8221; bottom_padding_tablet=&#8221;10%&#8221; left_padding_tablet=&#8221;10%&#8221; right_padding_tablet=&#8221;10%&#8221; top_padding_phone=&#8221;5%&#8221; bottom_padding_phone=&#8221;5%&#8221; left_padding_phone=&#8221;5%&#8221; right_padding_phone=&#8221;5%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#cfe6f6&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221; content_layout=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h2><span style=\"color: #009cdb; font-size: 40px;\">O teclado definitivo para iPad e Android<\/span><\/h2>\n[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<p style=\"font-size: 17px;\">Embora seja totalmente compat\u00edvel com Windows e Mac, este hardware est\u00e1 otimizado para desbloquear todo o potencial do iPadOS e dos tablets Android. Trata o seu tablet como o computador poderoso que ele \u00e9, oferecendo uma interface f\u00edsica que torna a escrita prolongada e a navega\u00e7\u00e3o complexa mais naturais. Emparelhe at\u00e9 tr\u00eas dispositivos em simult\u00e2neo via Bluetooth para gerir o seu tablet, telem\u00f3vel e port\u00e1til a partir de um \u00fanico centro.<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; vertically_center_columns=&#8221;true&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#cfe6f6&#8243; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;fade-in&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column left_padding_desktop=&#8221;35%&#8221; top_padding_tablet=&#8221;10%&#8221; bottom_padding_tablet=&#8221;10%&#8221; left_padding_tablet=&#8221;10%&#8221; right_padding_tablet=&#8221;10%&#8221; top_padding_phone=&#8221;5%&#8221; bottom_padding_phone=&#8221;5%&#8221; left_padding_phone=&#8221;5%&#8221; right_padding_phone=&#8221;5%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221; content_layout=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h2><span style=\"color: #009cdb; font-size: 40px;\">Liberdade sem fios para qualquer ambiente<\/span><\/h2>\n[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<p style=\"font-size: 17px;\">Quer esteja ligado a um desktop ou a trabalhar remotamente num tablet, a sua liga\u00e7\u00e3o mant\u00e9m-se est\u00e1vel. Utilize o recetor RF de 2.4 GHz para configura\u00e7\u00f5es tradicionais de PC ou recorra ao Bluetooth 5.1 para emparelhar instantaneamente com os seus dispositivos m\u00f3veis. Esta abordagem de modo duplo garante que nunca fica preso a um \u00fanico ecossistema, permitindo-lhe alternar entre dispositivos t\u00e3o rapidamente quanto muda de tarefa.<\/p>\n[\/vc_column_text][\/vc_column][vc_column top_padding_desktop=&#8221;70&#8243; bottom_padding_desktop=&#8221;70&#8243; left_padding_desktop=&#8221;70&#8243; right_padding_desktop=&#8221;70&#8243; top_padding_phone=&#8221;20&#8243; bottom_padding_phone=&#8221;20&#8243; left_padding_phone=&#8221;20&#8243; right_padding_phone=&#8221;20&#8243; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;center&#8221; tablet_text_alignment=&#8221;center&#8221; phone_text_alignment=&#8221;center&#8221; background_color=&#8221;#ffffff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;3px&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;bloco_redondo_2&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;3261&#8243; image_size=&#8221;full&#8221; max_width=&#8221;custom&#8221; animation_type=&#8221;looped&#8221; loop_animation=&#8221;none&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; constrain_group_1=&#8221;yes&#8221; constrain_group_2=&#8221;yes&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;custom&#8221; top_left_border_radius=&#8221;500&#8243; top_right_border_radius=&#8221;500&#8243; bottom_right_border_radius=&#8221;500&#8243; bottom_left_border_radius=&#8221;500&#8243; image_loading=&#8221;default&#8221; max_width_custom=&#8221;768&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#cfe6f6&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;20&#8243; bottom_padding=&#8221;20&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; id=&#8221;downloads&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;curve_opacity&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;3\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; el_id=&#8221;especificacoes&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][toggles style=&#8221;minimal&#8221; accordion=&#8221;true&#8221; accordion_starting_functionality=&#8221;default&#8221;][toggle color=&#8221;Default&#8221; heading_tag=&#8221;default&#8221; heading_tag_functionality=&#8221;default&#8221; title=&#8221;Caracter\u00edsticas&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<ul>\n<li data-section-id=\"180k1hg\" data-start=\"2356\" data-end=\"2386\">Teclado sem fios com suporte dobr\u00e1vel para tablets<\/li>\n<li data-section-id=\"180k1hg\" data-start=\"2356\" data-end=\"2386\">Liga\u00e7\u00e3o at\u00e9 4 dispositivos (1 via USB 2.4 GHz e 3 canais Bluetooth 5.1)<\/li>\n<li data-section-id=\"180k1hg\" data-start=\"2356\" data-end=\"2386\">Bateria recarreg\u00e1vel por USB-C com cerca de 150 horas de autonomia<\/li>\n<li data-section-id=\"180k1hg\" data-start=\"2356\" data-end=\"2386\">Layout em Portugu\u00eas com 79 teclas, incluindo 13 fun\u00e7\u00f5es de atalho Fn<\/li>\n<li data-section-id=\"180k1hg\" data-start=\"2356\" data-end=\"2386\">Perfil fino de apenas 12mm, com 390g de peso, ideal para a portabilidade do dia a dia<\/li>\n<li data-section-id=\"180k1hg\" data-start=\"2356\" data-end=\"2386\">Compat\u00edvel com iPadOS, Android, Windows, Mac e Linux<\/li>\n<\/ul>\n[\/vc_column_text][\/toggle][toggle color=&#8221;Default&#8221; heading_tag=&#8221;default&#8221; heading_tag_functionality=&#8221;default&#8221; title=&#8221;Especifica\u00e7\u00f5es&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>Layout:<\/strong> PT<\/p>\n<p><strong>Teclas:<\/strong><br \/>\n&#8211; 79<br \/>\n&#8211; 13 Fun\u00e7\u00f5es de atalho Fn: Reduzir luminosidade; Aumentar luminosidade; Desktops; Pesquisar; Reconhecimento de voz; Hibernar; Faixa anterior; Reproduzir \/ Pausar; Faixa seguinte; Mudo; Reduzir volume; Aumentar volume; Bloquear sess\u00e3o<\/p>\n<p><strong>Conex\u00f5es:<\/strong><br \/>\n&#8211; 2.4 GHz RF (Recetor USB)<br \/>\n&#8211; Bluetooth 5.1 (3 canais independentes, permitindo emparelhamento com 3 dispositivos diferentes)<br \/>\n&#8211; Dist\u00e2ncia de funcionamento: 8 m<\/p>\n<p><strong>Bateria:<\/strong><br \/>\n&#8211; 300 mAh L\u00edtio (recarreg\u00e1vel via USB-C)<br \/>\n&#8211; Autonomia: 150 horas (m\u00e9dia)<br \/>\n&#8211; Carregamento: 2 horas (carga completa)<br \/>\n&#8211; Voltagem: 3.7 V<br \/>\n&#8211; Corrente: Em funcionamento: 1.69 mA ~ 2.63 mA; Modo espera: 0.02 mA ~ 0.75 mA<br \/>\n&#8211; A pot\u00eancia de carregamento deve situar-se entre um m\u00ednimo de 0.1 Watts, exigido pelo equipamento, e um m\u00e1ximo de 1.15 Watts para alcan\u00e7ar a velocidade m\u00e1xima de carregamento<\/p>\n<p><strong>Dimens\u00f5es:<\/strong> 282 x 117 x 12 mm<br \/>\n<strong>Peso:<\/strong> 390 g<\/p>\n<p><strong>Compatibilidade:<\/strong><br \/>\n&#8211; Windows, Mac OS, Linux (2.4 GHz RF + Bluetooth)<br \/>\n&#8211; iPad OS, Android (Bluetooth)<\/p>\n<p><strong>Conte\u00fado da embalagem:<\/strong> Teclado com suporte para tablet; Recetor USB; Cabo USB-A &gt; USB-C 1 m; Guia do utilizador[\/vc_column_text][\/toggle][toggle color=&#8221;Default&#8221; heading_tag=&#8221;default&#8221; heading_tag_functionality=&#8221;default&#8221; title=&#8221;Log\u00edstica&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>Offy Pixie Tab<\/strong><br \/>\nSKU: OFFYPIXIETABPT<br \/>\nEAN: 5600413208175<\/p>\n<p><strong>Embalagem de expedi\u00e7\u00e3o:<\/strong><br \/>\n&#8211; Quantidade: 20<br \/>\n&#8211; Dimens\u00f5es: 355 x 315 x 270 mm<br \/>\n&#8211; Peso bruto: 12 kg[\/vc_column_text][\/toggle][\/toggles][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;rgba(230,245,251,0.01)&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;5px&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_color=&#8221;#009cdb&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text]\n<h3><span style=\"color: #009cdb;\">DOWNLOADS<\/span><\/h3>\n[\/vc_column_text][nectar_btn size=&#8221;large&#8221; open_new_tab=&#8221;true&#8221; button_style=&#8221;see-through-2&#8243; color_override=&#8221;#5c8191&#8243; hover_color_override=&#8221;#009cdb&#8221; hover_text_color_override=&#8221;#ffffff&#8221; icon_family=&#8221;fontawesome&#8221; url=&#8221;\/downloads\/pixie_tab\/offy_pixie_tab_datasheet.zip&#8221; text=&#8221;FICHA INFORMATIVA&#8221; css_animation=&#8221;fadeInUp&#8221; margin_top=&#8221;30%&#8221; margin_bottom=&#8221;10%&#8221; icon_fontawesome=&#8221;fa fa-file-o&#8221;][nectar_btn size=&#8221;large&#8221; open_new_tab=&#8221;true&#8221; button_style=&#8221;see-through-2&#8243; color_override=&#8221;#5c8191&#8243; hover_color_override=&#8221;#009cdb&#8221; hover_text_color_override=&#8221;#ffffff&#8221; icon_family=&#8221;fontawesome&#8221; url=&#8221;\/downloads\/pixie_tab\/offy_pixie_tab_images.zip&#8221; text=&#8221;IMAGENS&#8221; css_animation=&#8221;fadeInUp&#8221; icon_fontawesome=&#8221;fa fa-picture-o&#8221; margin_top=&#8221;10%&#8221; margin_bottom=&#8221;10%&#8221;][nectar_btn size=&#8221;large&#8221; open_new_tab=&#8221;true&#8221; button_style=&#8221;see-through-2&#8243; color_override=&#8221;#5c8191&#8243; hover_color_override=&#8221;#009cdb&#8221; hover_text_color_override=&#8221;#ffffff&#8221; icon_family=&#8221;fontawesome&#8221; url=&#8221;\/downloads\/pixie_tab\/offy_pixie_tab_user_guide.zip&#8221; text=&#8221;GUIA DO UTILIZADOR&#8221; css_animation=&#8221;fadeInUp&#8221; margin_top=&#8221;10%&#8221; icon_fontawesome=&#8221;fa fa-wrench&#8221;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; vertically_center_columns=&#8221;true&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding_tablet=&#8221;20&#8243; bottom_padding_tablet=&#8221;20&#8243; left_padding_tablet=&#8221;20&#8243; right_padding_tablet=&#8221;20&#8243; top_padding_phone=&#8221;20&#8243; bottom_padding_phone=&#8221;20&#8243; left_padding_phone=&#8221;20&#8243; right_padding_phone=&#8221;20&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; class=&#8221;product-row&#8221; id=&#8221;product-row&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3216","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Offy Pixie Tab - Teclado sem fios \/ Bluetooth com suporte para tablet<\/title>\n<meta name=\"description\" content=\"Aumente a sua produtividade com este teclado sem fios com suporte para tablet. Alterne entre 4 dispositivos e desfrute de 150h de autonomia. Compat\u00edvel com Windows, Mac, iPadOS e Android.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/offy.pt\/index.php\/teclados-pixie-tab\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Offy Pixie Tab - Teclado sem fios \/ Bluetooth com suporte para tablet\" \/>\n<meta property=\"og:description\" content=\"Aumente a sua produtividade com este teclado sem fios com suporte para tablet. Alterne entre 4 dispositivos e desfrute de 150h de autonomia. Compat\u00edvel com Windows, Mac, iPadOS e Android.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/offy.pt\/index.php\/teclados-pixie-tab\/\" \/>\n<meta property=\"og:site_name\" content=\"Offy\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-22T10:29:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/offy.pt\/wp-content\/uploads\/2026\/07\/2-01.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/offy.pt\\\/index.php\\\/teclados-pixie-tab\\\/\",\"url\":\"https:\\\/\\\/offy.pt\\\/index.php\\\/teclados-pixie-tab\\\/\",\"name\":\"Offy Pixie Tab - Teclado sem fios \\\/ Bluetooth com suporte para tablet\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/offy.pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/offy.pt\\\/index.php\\\/teclados-pixie-tab\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/offy.pt\\\/index.php\\\/teclados-pixie-tab\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/offy.pt\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/2-01.png\",\"datePublished\":\"2026-07-07T08:20:11+00:00\",\"dateModified\":\"2026-07-22T10:29:46+00:00\",\"description\":\"Aumente a sua produtividade com este teclado sem fios com suporte para tablet. Alterne entre 4 dispositivos e desfrute de 150h de autonomia. Compat\u00edvel com Windows, Mac, iPadOS e Android.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/offy.pt\\\/index.php\\\/teclados-pixie-tab\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/offy.pt\\\/index.php\\\/teclados-pixie-tab\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/offy.pt\\\/index.php\\\/teclados-pixie-tab\\\/#primaryimage\",\"url\":\"https:\\\/\\\/offy.pt\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/2-01.png\",\"contentUrl\":\"https:\\\/\\\/offy.pt\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/2-01.png\",\"width\":80,\"height\":80},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/offy.pt\\\/index.php\\\/teclados-pixie-tab\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/offy.pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pixie Tab &#8211; PT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/offy.pt\\\/#website\",\"url\":\"https:\\\/\\\/offy.pt\\\/\",\"name\":\"Offy - Equipamento de Escrit\u00f3rio\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/offy.pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Offy Pixie Tab - Teclado sem fios \/ Bluetooth com suporte para tablet","description":"Aumente a sua produtividade com este teclado sem fios com suporte para tablet. Alterne entre 4 dispositivos e desfrute de 150h de autonomia. Compat\u00edvel com Windows, Mac, iPadOS e Android.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/offy.pt\/index.php\/teclados-pixie-tab\/","og_locale":"en_GB","og_type":"article","og_title":"Offy Pixie Tab - Teclado sem fios \/ Bluetooth com suporte para tablet","og_description":"Aumente a sua produtividade com este teclado sem fios com suporte para tablet. Alterne entre 4 dispositivos e desfrute de 150h de autonomia. Compat\u00edvel com Windows, Mac, iPadOS e Android.","og_url":"https:\/\/offy.pt\/index.php\/teclados-pixie-tab\/","og_site_name":"Offy","article_modified_time":"2026-07-22T10:29:46+00:00","og_image":[{"url":"https:\/\/offy.pt\/wp-content\/uploads\/2026\/07\/2-01.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/offy.pt\/index.php\/teclados-pixie-tab\/","url":"https:\/\/offy.pt\/index.php\/teclados-pixie-tab\/","name":"Offy Pixie Tab - Teclado sem fios \/ Bluetooth com suporte para tablet","isPartOf":{"@id":"https:\/\/offy.pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/offy.pt\/index.php\/teclados-pixie-tab\/#primaryimage"},"image":{"@id":"https:\/\/offy.pt\/index.php\/teclados-pixie-tab\/#primaryimage"},"thumbnailUrl":"https:\/\/offy.pt\/wp-content\/uploads\/2026\/07\/2-01.png","datePublished":"2026-07-07T08:20:11+00:00","dateModified":"2026-07-22T10:29:46+00:00","description":"Aumente a sua produtividade com este teclado sem fios com suporte para tablet. Alterne entre 4 dispositivos e desfrute de 150h de autonomia. Compat\u00edvel com Windows, Mac, iPadOS e Android.","breadcrumb":{"@id":"https:\/\/offy.pt\/index.php\/teclados-pixie-tab\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/offy.pt\/index.php\/teclados-pixie-tab\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/offy.pt\/index.php\/teclados-pixie-tab\/#primaryimage","url":"https:\/\/offy.pt\/wp-content\/uploads\/2026\/07\/2-01.png","contentUrl":"https:\/\/offy.pt\/wp-content\/uploads\/2026\/07\/2-01.png","width":80,"height":80},{"@type":"BreadcrumbList","@id":"https:\/\/offy.pt\/index.php\/teclados-pixie-tab\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/offy.pt\/"},{"@type":"ListItem","position":2,"name":"Pixie Tab &#8211; PT"}]},{"@type":"WebSite","@id":"https:\/\/offy.pt\/#website","url":"https:\/\/offy.pt\/","name":"Offy - Equipamento de Escrit\u00f3rio","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/offy.pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/offy.pt\/index.php\/wp-json\/wp\/v2\/pages\/3216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/offy.pt\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/offy.pt\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/offy.pt\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/offy.pt\/index.php\/wp-json\/wp\/v2\/comments?post=3216"}],"version-history":[{"count":34,"href":"https:\/\/offy.pt\/index.php\/wp-json\/wp\/v2\/pages\/3216\/revisions"}],"predecessor-version":[{"id":3597,"href":"https:\/\/offy.pt\/index.php\/wp-json\/wp\/v2\/pages\/3216\/revisions\/3597"}],"wp:attachment":[{"href":"https:\/\/offy.pt\/index.php\/wp-json\/wp\/v2\/media?parent=3216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}